{"id":11164,"date":"2025-12-18T12:58:37","date_gmt":"2025-12-18T15:58:37","guid":{"rendered":"https:\/\/solvefortomorrowlatam.com\/pratica\/irrigacao-inteligente-jovens-da-nicaragua-inovam-na-agricultura-sustentavel\/"},"modified":"2025-12-18T13:34:33","modified_gmt":"2025-12-18T16:34:33","slug":"riego-inteligente-jovenes-de-nicaragua-innovan-en-la-agricultura","status":"publish","type":"pratica","link":"https:\/\/solvefortomorrowlatam.com\/es\/practica\/riego-inteligente-jovenes-de-nicaragua-innovan-en-la-agricultura\/","title":{"rendered":"J\u00f3venes desarrollan un sistema de riego inteligente para mejorar la realidad rural de su comunidad"},"content":{"rendered":"\n<p>Nicaragua es conocida como el granero de Centroam\u00e9rica: algod\u00f3n, caf\u00e9 y otros cultivos crecen en las planicies f\u00e9rtiles del peque\u00f1o pa\u00eds, y muchas personas &#8211;<\/p>\n\n\n\n<p>&nbsp;en las grandes y peque\u00f1as ciudades &#8211;&nbsp; son productores rurales. J\u00f3venes de la parte rural de la capital Managua, hijos de agricultores, se preguntaron: \u00bfqu\u00e9 es posible hacer para tornar el trabajo en las plantaciones m\u00e1s optimizado?&nbsp;<\/p>\n\n\n\n<p>Un sistema de riego automatizado pareci\u00f3 la mejor soluci\u00f3n para el grupo de estudiantes&nbsp; finalistas de Nicaragua&nbsp; en la edici\u00f3n 2024 de Solve for Tomorrow \u2013 Regi\u00f3n Centroam\u00e9rica y el Caribe. El proyecto \u201cSistema de Riego Sensorial\u201d consiste en un sistema inteligente de riego que utiliza sensores para medir la humedad del suelo y ahorrar el uso del \u00e1gua, evitando desperdicios y mejorando la eficiencia de las cosechas.&nbsp;<\/p>\n\n\n\n<p>Los estudiantes del noveno grado (en Nicaragua, es el antepen\u00faltimo a\u00f1o de la escolarizaci\u00f3n obligatoria) tuvieron la idea solos, observando los desaf\u00edos de sus familias y de las <a href=\"https:\/\/solvefortomorrowlatam.com\/es\/entrada\/comunidade\/\" target=\"_blank\" rel=\"noreferrer noopener\">comunidades<\/a>, que lidian las plantaciones, como cuenta el <a href=\"https:\/\/solvefortomorrowlatam.com\/es\/entrada\/profesor-mediador\/\" target=\"_blank\" rel=\"noreferrer noopener\">profesor mediador<\/a> Gerald Jes\u00fas. &#8220;Los j\u00f3venes ya ten\u00edan idea de lo que quer\u00edan. La comunidad donde est\u00e1n tiene mucha semilla. Son hijos de productores, est\u00e1n acostumbrados con ese tema. Quer\u00edan hacer la transformaci\u00f3n en la vida de sus familias.\u201d\u00a0<\/p>\n\n\n\n<p>Jes\u00fas lleg\u00f3 con el proyecto pr\u00e1cticamente ideado: los estudiantes entend\u00edan que no ser\u00eda posible hacer un sistema por entero,&nbsp; pero s\u00ed una maqueta, y para tanto, necesitaban de alg\u00fan experto de programaci\u00f3n. El profesor universitario ya ense\u00f1aba dentro de la escuela, pero fue invitado de manera especial por los estudiantes para el proyecto. Fue la primera vez que trabaj\u00f3 con j\u00f3venes tan peque\u00f1os.<\/p>\n\n\n\n<p><strong>Programaci\u00f3n y buenos testeos. Presentaci\u00f3n a mejorar<\/strong><\/p>\n\n\n\n<p>La idea del sistema se resum\u00eda en un dispositivo que pudiera ser accionado desde cualquier lugar, y que estuviera conectado con las partes comunes de&nbsp; un plant\u00edo, controlando la irrigaci\u00f3n a depender de las condiciones del suelo. Como la energ\u00eda es intermitente en la zona rural, la idea es que el sistema fuera alimentado por paneles solares.&nbsp;<\/p>\n\n\n\n<p>\u201cEl primer paso fue crear un diagrama de bloque, con todos los componentes que \u00edbamos a utilizar en el modelo de la vida real, como sensores de humedad y temperatura, una bomba de agua para regular la cantidad de agua, y tambi\u00e9n los paneles solares\u201d, recuerda el profesor. El Arduino, plataforma de hardware y software de <a href=\"https:\/\/solvefortomorrowlatam.com\/es\/entrada\/codigo-abierto-educacion\/\" target=\"_blank\" rel=\"noreferrer noopener\">c\u00f3digo abierto<\/a>, fue elegida porque era m\u00e1s sencilla, facilitando el aprendizaje de programaci\u00f3n para estudiantes que nunca tuvieron contacto con el tema.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"573\" src=\"https:\/\/solvefortomorrowlatam.com\/wp-content\/uploads\/2025\/12\/NIC_Sistema-de-Riego-Sensorial-1024x573.png\" alt=\"\" class=\"wp-image-11156\" srcset=\"https:\/\/solvefortomorrowlatam.com\/wp-content\/uploads\/2025\/12\/NIC_Sistema-de-Riego-Sensorial-1024x573.png 1024w, https:\/\/solvefortomorrowlatam.com\/wp-content\/uploads\/2025\/12\/NIC_Sistema-de-Riego-Sensorial-300x168.png 300w, https:\/\/solvefortomorrowlatam.com\/wp-content\/uploads\/2025\/12\/NIC_Sistema-de-Riego-Sensorial-768x429.png 768w, https:\/\/solvefortomorrowlatam.com\/wp-content\/uploads\/2025\/12\/NIC_Sistema-de-Riego-Sensorial-1536x859.png 1536w, https:\/\/solvefortomorrowlatam.com\/wp-content\/uploads\/2025\/12\/NIC_Sistema-de-Riego-Sensorial-2048x1145.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>El prototipo emula las condiciones de una plantaci\u00f3n donde el sistema de irrigaci\u00f3n inteligente puede aplicarse.<\/em><\/figcaption><\/figure>\n\n\n\n<p>La parte de la programaci\u00f3n fue m\u00e1s demorada.\u201cSe nos hizo chiquito el tiempo. Lo hablo de mi parte y de los j\u00f3venes tambi\u00e9n. Estaban un poco presionados porque ten\u00edan la idea, eran muy buenos, pero hab\u00edan puntos de programaci\u00f3n que ellos no manejaban. Cuando llegaron a m\u00ed, yo ya ten\u00eda otra perspectiva de c\u00f3mo construir y lo hicimos en lo que cabe con su estudio y en mi trabajo.\u201d&nbsp;<\/p>\n\n\n\n<p>Para llegar hasta un prototipo que reflejara los efectos del sistema en una plantaci\u00f3n, los estudiantes utilizaron los siguientes materiales: sensores de humedad y de temperatura, una bomba de 5V, transformadores, bater\u00eda, paneles solares y convertidores.&nbsp;<\/p>\n\n\n\n<p>Las pruebas de duraci\u00f3n de la bater\u00eda del prototipo, que duraba entre 3 y 4 d\u00edas, fueron buenas. El grupo entendi\u00f3 que podr\u00eda concentrarse en las presentaciones del <em>pitch<\/em> del proyecto, dado que eran t\u00edmidos. \u201cNos enfocamos bastante en la parte de la exposici\u00f3n, que a los muchachos les costaba mucho. Tocar un proyecto que para ellos era algo nuevo y aprenderse t\u00e9rminos, expresarse de tal manera, a ellos les cost\u00f3 mucho, pero se logr\u00f3.\u201d Para entrenar, los estudiantes presentaron el prototipo para otros cursos del colegio.&nbsp;<\/p>\n\n\n\n<p><strong>Una experiencia nueva para los estudiantes y para el profesor&nbsp;<\/strong><\/p>\n\n\n\n<p>Aunque tuviera una larga experiencia con programaci\u00f3n, fue la primera vez que el profesor Jes\u00fas trabaj\u00f3 junto con estudiantes m\u00e1s j\u00f3venes. Hubo desaf\u00edos pedag\u00f3gicos en el encuentro porque, diferente del ambiente universitario, donde las personas pueden salir cuando quieran, fue necesaria la disciplina y tambi\u00e9n trabajar en per\u00edodos fuera de hora de clases que los padres de los j\u00f3venes autorizaron.&nbsp;<\/p>\n\n\n\n<div class=\"banner -yellow\">\n    <h5>\n                Tip!    <\/h5>\n    <p>Para profesores que no tienen experiencia en trabajar con j\u00f3venes, pero son invitados a hacer parte de proyectos STEM, el profesor Jes\u00fas les aconseja  abrir sus mentes: \u201cEl \u00fanico consejo que les dar\u00eda yo es que sean comprometidos con los estudiantes porque ellos se esfuerzan bastante. A ellos les gusta y les llama la atenci\u00f3n. Aunque a m\u00ed me tocara la parte de programaci\u00f3n, que fue mi \u00e1rea fuerte, eso no significa que nosotros no pod\u00edamos abarcar otros temas. Ahora la informaci\u00f3n est\u00e1 bastante a la mano, es muy f\u00e1cil investigar y aprovechar los recursos que tenemos.\u201d <\/p>\n<\/div>\n\n\n<p>Ahora que el <a href=\"https:\/\/solvefortomorrowlatam.com\/es\/entrada\/prototipo-educacion-stem\/\" target=\"_blank\" rel=\"noreferrer noopener\">prototipo<\/a> fue finalista y tiene la posibilidad de crecer, el profesor cree que los estudiantes entender\u00e1n c\u00f3mo los conocimientos cient\u00edficos pueden ser utilizados para mejorar la vida de sus territorios y comunidades. M\u00e1s all\u00e1 de crear un proyecto en la escuela, los estudiantes pueden ayudar a sus familias y planear futuros donde logren desarrollar sus propios cultivos.\u00a0<\/p>\n\n\n\n<p>Jes\u00fas apunta que la iniciativa Solve for Tomorrow es una oportunidad donde se muestra que cualquier estudiante, de cualquier regi\u00f3n o pa\u00eds, puede desarrollar un proyecto \u00fanico: \u201cMe encant\u00f3 saber que est\u00e1bamos participando contra muchos pa\u00edses, como Costa Rica y Rep\u00fablica Dominicana. Y al ver el nivel acad\u00e9mico de otros pa\u00edses con respecto a nosotros&nbsp; percibir que tenemos las mismas capacidades, la misma oportunidad de competir\u201d.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"embed-responsive embed-responsive-16by9 ratio ratio-16x9\"><iframe loading=\"lazy\" class=\"embed-responsive-item\"  title=\"Nicaragua - Sistema de Riego Sensorial - Centro Educativo Sor Mar\u00eda Romero\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/8MQr4txRNe4?list=PLBo_JZU9yOMnxaLFqdlM33jeORUP9a42R\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Enfrentando el reto del tiempo y de presentarse con timidez, los estudiantes tuvieron la ayuda de un maestro externo a la escuela para montar la programaci\u00f3n del sistema. <\/p>\n","protected":false},"featured_media":11155,"template":"","tags":[2451,2444,2414,2420,1699,2445,2450,2449,731,2446,2447,2448],"eixo_tematico":[206],"area_stem":[211,168,170],"ano_projeto":[1260],"posicao_projeto":[229],"pais_projeto":[191],"area_conhecimento":[252],"class_list":["post-11164","pratica","type-pratica","status-publish","has-post-thumbnail","hentry","tag-agricultura-sostenible","tag-agricultura-sustentavel","tag-educacao-cientifica","tag-educacion-cientifica","tag-innovacion-educativa","tag-irrigacao-inteligente","tag-riego-inteligente","tag-sostenibilidad-ambiental","tag-stem-2","tag-sustentabilidade-ambiental","tag-tecnologia-rural","tag-tecnologia-rural-2","eixo_tematico-meio-ambiente-es","area_stem-ciencias-es","area_stem-engenharia-es","area_stem-tecnologia-es","ano_projeto-1260","posicao_projeto-finalista-es","pais_projeto-nicaragua-es","area_conhecimento-educacao-ambiental-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>J\u00f3venes desarrollan un sistema de riego inteligente para mejorar la realidad rural de su comunidad | Solve for Tomorrow Latam<\/title>\n<meta name=\"description\" content=\"Conoce c\u00f3mo estudiantes de Nicaragua crearon un sistema de riego inteligente con sensores y energ\u00eda solar para optimizar el uso del agua en la agricultura.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solvefortomorrowlatam.com\/es\/practica\/riego-inteligente-jovenes-de-nicaragua-innovan-en-la-agricultura\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"J\u00f3venes desarrollan un sistema de riego inteligente para mejorar la realidad rural de su comunidad | Solve for Tomorrow Latam\" \/>\n<meta property=\"og:description\" content=\"Conoce c\u00f3mo estudiantes de Nicaragua crearon un sistema de riego inteligente con sensores y energ\u00eda solar para optimizar el uso del agua en la agricultura.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solvefortomorrowlatam.com\/es\/practica\/riego-inteligente-jovenes-de-nicaragua-innovan-en-la-agricultura\/\" \/>\n<meta property=\"og:site_name\" content=\"Solve for Tomorrow Latam\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-18T16:34:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/solvefortomorrowlatam.com\/wp-content\/uploads\/2025\/12\/img_desk_SFT_riego.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"570\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/solvefortomorrowlatam.com\\\/es\\\/practica\\\/riego-inteligente-jovenes-de-nicaragua-innovan-en-la-agricultura\\\/\",\"url\":\"https:\\\/\\\/solvefortomorrowlatam.com\\\/es\\\/practica\\\/riego-inteligente-jovenes-de-nicaragua-innovan-en-la-agricultura\\\/\",\"name\":\"J\u00f3venes desarrollan un sistema de riego inteligente para mejorar la realidad rural de su comunidad | Solve for Tomorrow Latam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solvefortomorrowlatam.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/solvefortomorrowlatam.com\\\/es\\\/practica\\\/riego-inteligente-jovenes-de-nicaragua-innovan-en-la-agricultura\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/solvefortomorrowlatam.com\\\/es\\\/practica\\\/riego-inteligente-jovenes-de-nicaragua-innovan-en-la-agricultura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solvefortomorrowlatam.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/img_desk_SFT_riego.png\",\"datePublished\":\"2025-12-18T15:58:37+00:00\",\"dateModified\":\"2025-12-18T16:34:33+00:00\",\"description\":\"Conoce c\u00f3mo estudiantes de Nicaragua crearon un sistema de riego inteligente con sensores y energ\u00eda solar para optimizar el uso del agua en la agricultura.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solvefortomorrowlatam.com\\\/es\\\/practica\\\/riego-inteligente-jovenes-de-nicaragua-innovan-en-la-agricultura\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/solvefortomorrowlatam.com\\\/es\\\/practica\\\/riego-inteligente-jovenes-de-nicaragua-innovan-en-la-agricultura\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/solvefortomorrowlatam.com\\\/es\\\/practica\\\/riego-inteligente-jovenes-de-nicaragua-innovan-en-la-agricultura\\\/#primaryimage\",\"url\":\"https:\\\/\\\/solvefortomorrowlatam.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/img_desk_SFT_riego.png\",\"contentUrl\":\"https:\\\/\\\/solvefortomorrowlatam.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/img_desk_SFT_riego.png\",\"width\":1920,\"height\":570,\"caption\":\"Estudiantes desarrollan una soluci\u00f3n de riego inteligente que combina innovaci\u00f3n cient\u00edfica, sostenibilidad y compromiso con sus comunidades.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solvefortomorrowlatam.com\\\/es\\\/practica\\\/riego-inteligente-jovenes-de-nicaragua-innovan-en-la-agricultura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/solvefortomorrowlatam.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"J\u00f3venes desarrollan un sistema de riego inteligente para mejorar la realidad rural de su comunidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solvefortomorrowlatam.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/solvefortomorrowlatam.com\\\/es\\\/\",\"name\":\"Solve for Tomorrow Latam\",\"description\":\"A\u00e7\u00f5es educativas para empoderar jovens na transforma\u00e7\u00e3o da sociedade\",\"publisher\":{\"@id\":\"https:\\\/\\\/solvefortomorrowlatam.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solvefortomorrowlatam.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solvefortomorrowlatam.com\\\/es\\\/#organization\",\"name\":\"Samsung Solve for Tomorrow Latam\",\"url\":\"https:\\\/\\\/solvefortomorrowlatam.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/solvefortomorrowlatam.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/solvefortomorrowlatam.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/solvefortomorrowlatam.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Samsung Solve for Tomorrow Latam\"},\"image\":{\"@id\":\"https:\\\/\\\/solvefortomorrowlatam.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"J\u00f3venes desarrollan un sistema de riego inteligente para mejorar la realidad rural de su comunidad | Solve for Tomorrow Latam","description":"Conoce c\u00f3mo estudiantes de Nicaragua crearon un sistema de riego inteligente con sensores y energ\u00eda solar para optimizar el uso del agua en la agricultura.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solvefortomorrowlatam.com\/es\/practica\/riego-inteligente-jovenes-de-nicaragua-innovan-en-la-agricultura\/","og_locale":"es_ES","og_type":"article","og_title":"J\u00f3venes desarrollan un sistema de riego inteligente para mejorar la realidad rural de su comunidad | Solve for Tomorrow Latam","og_description":"Conoce c\u00f3mo estudiantes de Nicaragua crearon un sistema de riego inteligente con sensores y energ\u00eda solar para optimizar el uso del agua en la agricultura.","og_url":"https:\/\/solvefortomorrowlatam.com\/es\/practica\/riego-inteligente-jovenes-de-nicaragua-innovan-en-la-agricultura\/","og_site_name":"Solve for Tomorrow Latam","article_modified_time":"2025-12-18T16:34:33+00:00","og_image":[{"width":1920,"height":570,"url":"https:\/\/solvefortomorrowlatam.com\/wp-content\/uploads\/2025\/12\/img_desk_SFT_riego.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/solvefortomorrowlatam.com\/es\/practica\/riego-inteligente-jovenes-de-nicaragua-innovan-en-la-agricultura\/","url":"https:\/\/solvefortomorrowlatam.com\/es\/practica\/riego-inteligente-jovenes-de-nicaragua-innovan-en-la-agricultura\/","name":"J\u00f3venes desarrollan un sistema de riego inteligente para mejorar la realidad rural de su comunidad | Solve for Tomorrow Latam","isPartOf":{"@id":"https:\/\/solvefortomorrowlatam.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/solvefortomorrowlatam.com\/es\/practica\/riego-inteligente-jovenes-de-nicaragua-innovan-en-la-agricultura\/#primaryimage"},"image":{"@id":"https:\/\/solvefortomorrowlatam.com\/es\/practica\/riego-inteligente-jovenes-de-nicaragua-innovan-en-la-agricultura\/#primaryimage"},"thumbnailUrl":"https:\/\/solvefortomorrowlatam.com\/wp-content\/uploads\/2025\/12\/img_desk_SFT_riego.png","datePublished":"2025-12-18T15:58:37+00:00","dateModified":"2025-12-18T16:34:33+00:00","description":"Conoce c\u00f3mo estudiantes de Nicaragua crearon un sistema de riego inteligente con sensores y energ\u00eda solar para optimizar el uso del agua en la agricultura.","breadcrumb":{"@id":"https:\/\/solvefortomorrowlatam.com\/es\/practica\/riego-inteligente-jovenes-de-nicaragua-innovan-en-la-agricultura\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solvefortomorrowlatam.com\/es\/practica\/riego-inteligente-jovenes-de-nicaragua-innovan-en-la-agricultura\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/solvefortomorrowlatam.com\/es\/practica\/riego-inteligente-jovenes-de-nicaragua-innovan-en-la-agricultura\/#primaryimage","url":"https:\/\/solvefortomorrowlatam.com\/wp-content\/uploads\/2025\/12\/img_desk_SFT_riego.png","contentUrl":"https:\/\/solvefortomorrowlatam.com\/wp-content\/uploads\/2025\/12\/img_desk_SFT_riego.png","width":1920,"height":570,"caption":"Estudiantes desarrollan una soluci\u00f3n de riego inteligente que combina innovaci\u00f3n cient\u00edfica, sostenibilidad y compromiso con sus comunidades."},{"@type":"BreadcrumbList","@id":"https:\/\/solvefortomorrowlatam.com\/es\/practica\/riego-inteligente-jovenes-de-nicaragua-innovan-en-la-agricultura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/solvefortomorrowlatam.com\/es\/"},{"@type":"ListItem","position":2,"name":"J\u00f3venes desarrollan un sistema de riego inteligente para mejorar la realidad rural de su comunidad"}]},{"@type":"WebSite","@id":"https:\/\/solvefortomorrowlatam.com\/es\/#website","url":"https:\/\/solvefortomorrowlatam.com\/es\/","name":"Solve for Tomorrow Latam","description":"A\u00e7\u00f5es educativas para empoderar jovens na transforma\u00e7\u00e3o da sociedade","publisher":{"@id":"https:\/\/solvefortomorrowlatam.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solvefortomorrowlatam.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/solvefortomorrowlatam.com\/es\/#organization","name":"Samsung Solve for Tomorrow Latam","url":"https:\/\/solvefortomorrowlatam.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/solvefortomorrowlatam.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/solvefortomorrowlatam.com\/wp-content\/uploads\/2022\/08\/cropped-favicon.png","contentUrl":"https:\/\/solvefortomorrowlatam.com\/wp-content\/uploads\/2022\/08\/cropped-favicon.png","width":512,"height":512,"caption":"Samsung Solve for Tomorrow Latam"},"image":{"@id":"https:\/\/solvefortomorrowlatam.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/solvefortomorrowlatam.com\/es\/wp-json\/wp\/v2\/pratica\/11164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solvefortomorrowlatam.com\/es\/wp-json\/wp\/v2\/pratica"}],"about":[{"href":"https:\/\/solvefortomorrowlatam.com\/es\/wp-json\/wp\/v2\/types\/pratica"}],"version-history":[{"count":0,"href":"https:\/\/solvefortomorrowlatam.com\/es\/wp-json\/wp\/v2\/pratica\/11164\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solvefortomorrowlatam.com\/es\/wp-json\/wp\/v2\/media\/11155"}],"wp:attachment":[{"href":"https:\/\/solvefortomorrowlatam.com\/es\/wp-json\/wp\/v2\/media?parent=11164"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/solvefortomorrowlatam.com\/es\/wp-json\/wp\/v2\/tags?post=11164"},{"taxonomy":"eixo_tematico","embeddable":true,"href":"https:\/\/solvefortomorrowlatam.com\/es\/wp-json\/wp\/v2\/eixo_tematico?post=11164"},{"taxonomy":"area_stem","embeddable":true,"href":"https:\/\/solvefortomorrowlatam.com\/es\/wp-json\/wp\/v2\/area_stem?post=11164"},{"taxonomy":"ano_projeto","embeddable":true,"href":"https:\/\/solvefortomorrowlatam.com\/es\/wp-json\/wp\/v2\/ano_projeto?post=11164"},{"taxonomy":"posicao_projeto","embeddable":true,"href":"https:\/\/solvefortomorrowlatam.com\/es\/wp-json\/wp\/v2\/posicao_projeto?post=11164"},{"taxonomy":"pais_projeto","embeddable":true,"href":"https:\/\/solvefortomorrowlatam.com\/es\/wp-json\/wp\/v2\/pais_projeto?post=11164"},{"taxonomy":"area_conhecimento","embeddable":true,"href":"https:\/\/solvefortomorrowlatam.com\/es\/wp-json\/wp\/v2\/area_conhecimento?post=11164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}